{"id":7549,"date":"2025-02-12T06:51:59","date_gmt":"2025-02-12T06:51:59","guid":{"rendered":"https:\/\/www.kscranegroup.com\/?post_type=posts&#038;p=7549"},"modified":"2025-02-12T07:24:07","modified_gmt":"2025-02-12T07:24:07","slug":"30-cranes-exported-to-malaysia","status":"publish","type":"posts","link":"https:\/\/www.kscranegroup.com\/pt\/posts\/30-cranes-exported-to-malaysia\/","title":{"rendered":"30 guindastes exportados para a Mal\u00e1sia"},"content":{"rendered":"<p>Na nova jornada de 2025, nossa empresa recebeu pedidos internacionais cont\u00ednuos e boas not\u00edcias. Em 2 de janeiro de 2025, tivemos o prazer de concluir o projeto de entrega de 30 guindastes para a Mal\u00e1sia.<\/p>\n\n\n\n<p>Antes da partida, nossos representantes da empresa e representantes da Mal\u00e1sia realizaram uma cerim\u00f4nia para entregar os guindastes. Durante a cerim\u00f4nia, nosso presidente, Wu Gaoxuan, fez um discurso importante. Em seu discurso, ele primeiro afirmou a qualidade e a seguran\u00e7a de nossos produtos e enfatizou que este lote de guindastes apresenta tecnologia de controle de convers\u00e3o de frequ\u00eancia digital inteligente, tecnologia de posicionamento antibalan\u00e7o preciso e tecnologia de interconex\u00e3o de informa\u00e7\u00f5es inteligente. Esses guindastes tamb\u00e9m incluem recursos importantes, como controle de emerg\u00eancia, anticolis\u00e3o inteligente e detec\u00e7\u00e3o de limite excedido. Em segundo lugar, comemoramos a conclus\u00e3o bem-sucedida deste projeto por <a href=\"https:\/\/www.kscranegroup.com\/pt\/about-us.html\">Guindaste Henan Kuangshan<\/a>. Por fim, expressamos nossa esperan\u00e7a de que esses 30 guindastes sejam entregues \u00e0 Mal\u00e1sia com rapidez e seguran\u00e7a.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.kscranegroup.com\/wp-content\/uploads\/2025\/02\/30-cranes-exported-to-Malaysia2.jpg\" alt=\"\" class=\"wp-image-7551\" srcset=\"https:\/\/www.kscranegroup.com\/wp-content\/uploads\/2025\/02\/30-cranes-exported-to-Malaysia2.jpg 1620w, https:\/\/www.kscranegroup.com\/wp-content\/uploads\/2025\/02\/30-cranes-exported-to-Malaysia2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/figure>\n\n\n\n<p>A conclus\u00e3o deste projeto n\u00e3o apenas demonstra as fortes capacidades da nossa empresa, mas tamb\u00e9m fornece equipamentos de eleva\u00e7\u00e3o mais inteligentes e seguros, juntamente com solu\u00e7\u00f5es abrangentes, para pa\u00edses que participam da constru\u00e7\u00e3o da Iniciativa Cintur\u00e3o e Rota. Isso consolida e aprimora ainda mais nossa competitividade internacional. Continuaremos a fazer esfor\u00e7os persistentes, embarcar em uma jornada gloriosa e alcan\u00e7ar um sucesso ainda maior.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.kscranegroup.com\/wp-content\/uploads\/2025\/02\/30-cranes-exported-to-Malaysia3.jpg\" alt=\"\" class=\"wp-image-7552\" srcset=\"https:\/\/www.kscranegroup.com\/wp-content\/uploads\/2025\/02\/30-cranes-exported-to-Malaysia3.jpg 1620w, https:\/\/www.kscranegroup.com\/wp-content\/uploads\/2025\/02\/30-cranes-exported-to-Malaysia3-1536x1024.jpg 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"Na nova jornada de 2025, nossa empresa recebeu pedidos internacionais cont\u00ednuos e boas not\u00edcias. Em 2 de janeiro de 2025, tivemos o prazer de concluir o projeto de entrega de 30 guindastes para a Mal\u00e1sia. Antes da partida, nossos representantes da empresa e representantes da Mal\u00e1sia realizaram uma cerim\u00f4nia para entregar os guindastes. Durante a cerim\u00f4nia, nosso presidente, Wu [\u2026]","protected":false},"featured_media":7553,"parent":0,"menu_order":0,"template":"single-blog.php","posts_category":[15],"posts_tag":[86],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/xmxposts\/7549"}],"collection":[{"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/xmxposts"}],"about":[{"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/types\/posts"}],"version-history":[{"count":2,"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/xmxposts\/7549\/revisions"}],"predecessor-version":[{"id":7555,"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/xmxposts\/7549\/revisions\/7555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/media\/7553"}],"wp:attachment":[{"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/media?parent=7549"}],"wp:term":[{"taxonomy":"posts_category","embeddable":true,"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/posts_category?post=7549"},{"taxonomy":"posts_tag","embeddable":true,"href":"https:\/\/www.kscranegroup.com\/pt\/wp-json\/wp\/v2\/posts_tag?post=7549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}